{"id":5258,"date":"2018-03-06T13:26:11","date_gmt":"2018-03-06T12:26:11","guid":{"rendered":"https:\/\/op.fanfiktion.de\/?p=5258"},"modified":"2018-03-20T16:50:56","modified_gmt":"2018-03-20T15:50:56","slug":"tutorien-themen-und-organisatorisches","status":"publish","type":"post","link":"https:\/\/op.fanfiktion.de\/index.php\/5258\/tutorien-themen-und-organisatorisches\/","title":{"rendered":"Tutorien &#8211; Themen und Organisatorisches + Nachtrag"},"content":{"rendered":"<div class=\"shariff shariff-align-left shariff-widget-align-left\"><ul class=\"shariff-buttons theme-white orientation-horizontal buttonsize-small\"><li class=\"shariff-button twitter shariff-nocustomcolor\" style=\"background-color:#595959\"><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Fop.fanfiktion.de%2Findex.php%2F5258%2Ftutorien-themen-und-organisatorisches%2F&text=Tutorien%20%E2%80%93%20Themen%20und%20Organisatorisches%20%2B%20Nachtrag&via=fanfiktionde\" title=\"Bei X teilen\" aria-label=\"Bei X teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#000; color:#000\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#000\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\"><path fill=\"#000\" d=\"M14.258 10.152L23.176 0h-2.113l-7.747 8.813L7.133 0H0l9.352 13.328L0 23.973h2.113l8.176-9.309 6.531 9.309h7.133zm-2.895 3.293l-.949-1.328L2.875 1.56h3.246l6.086 8.523.945 1.328 7.91 11.078h-3.246zm0 0\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#000\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button reddit shariff-nocustomcolor\" style=\"background-color:#ff5700\"><a href=\"https:\/\/www.reddit.com\/submit?url=https%3A%2F%2Fop.fanfiktion.de%2Findex.php%2F5258%2Ftutorien-themen-und-organisatorisches%2F\" title=\"Bei Reddit teilen\" aria-label=\"Bei Reddit teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#ff4500; color:#ff4500\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#ff4500\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path fill=\"#ff4500\" d=\"M440.3 203.5c-15 0-28.2 6.2-37.9 15.9-35.7-24.7-83.8-40.6-137.1-42.3L293 52.3l88.2 19.8c0 21.6 17.6 39.2 39.2 39.2 22 0 39.7-18.1 39.7-39.7s-17.6-39.7-39.7-39.7c-15.4 0-28.7 9.3-35.3 22l-97.4-21.6c-4.9-1.3-9.7 2.2-11 7.1L246.3 177c-52.9 2.2-100.5 18.1-136.3 42.8-9.7-10.1-23.4-16.3-38.4-16.3-55.6 0-73.8 74.6-22.9 100.1-1.8 7.9-2.6 16.3-2.6 24.7 0 83.8 94.4 151.7 210.3 151.7 116.4 0 210.8-67.9 210.8-151.7 0-8.4-.9-17.2-3.1-25.1 49.9-25.6 31.5-99.7-23.8-99.7zM129.4 308.9c0-22 17.6-39.7 39.7-39.7 21.6 0 39.2 17.6 39.2 39.7 0 21.6-17.6 39.2-39.2 39.2-22 .1-39.7-17.6-39.7-39.2zm214.3 93.5c-36.4 36.4-139.1 36.4-175.5 0-4-3.5-4-9.7 0-13.7 3.5-3.5 9.7-3.5 13.2 0 27.8 28.5 120 29 149 0 3.5-3.5 9.7-3.5 13.2 0 4.1 4 4.1 10.2.1 13.7zm-.8-54.2c-21.6 0-39.2-17.6-39.2-39.2 0-22 17.6-39.7 39.2-39.7 22 0 39.7 17.6 39.7 39.7-.1 21.5-17.7 39.2-39.7 39.2z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#ff4500\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button tumblr shariff-nocustomcolor\" style=\"background-color:#529ecc\"><a href=\"https:\/\/www.tumblr.com\/widgets\/share\/tool?posttype=link&canonicalUrl=https%3A%2F%2Fop.fanfiktion.de%2Findex.php%2F5258%2Ftutorien-themen-und-organisatorisches%2F&tags=op.fanfiktion.de\" title=\"Bei tumblr teilen\" aria-label=\"Bei tumblr teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#36465d; color:#36465d\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#36465d\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#36465d\" d=\"M18 14l0 7.3c0 1.9 0 2.9 0.2 3.5 0.2 0.5 0.7 1.1 1.2 1.4 0.7 0.4 1.5 0.6 2.4 0.6 1.6 0 2.6-0.2 4.2-1.3v4.8c-1.4 0.6-2.6 1-3.7 1.3-1.1 0.3-2.3 0.4-3.6 0.4-1.5 0-2.3-0.2-3.4-0.6-1.1-0.4-2.1-0.9-2.9-1.6-0.8-0.7-1.3-1.4-1.7-2.2s-0.5-1.9-0.5-3.4v-11.2h-4.3v-4.5c1.3-0.4 2.7-1 3.6-1.8 0.9-0.8 1.6-1.7 2.2-2.7 0.5-1.1 0.9-2.4 1.1-4.1h5.2l0 8h8v6h-8z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#36465d\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fop.fanfiktion.de%2Findex.php%2F5258%2Ftutorien-themen-und-organisatorisches%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#0077b5\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#0077b5\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#0077b5\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fop.fanfiktion.de%2Findex.php%2F5258%2Ftutorien-themen-und-organisatorisches%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#3b5998\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#3b5998\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#3b5998\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#a8a8a8\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#999; color:#999\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#999\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div><p><strong>Nachtrag &#8211; 20.03.2018<\/strong><\/p>\n<p>Ich habe die Kommentarfunktion f\u00fcr diesen Beitrag geschlossen. Die Themenliste in diesem Beitrag wird <strong>NICHT MEHR<\/strong> aktualisiert. Die aktuelle Liste findet ihr im <a href=\"https:\/\/forum.fanfiktion.de\/t\/54262\/1\/54262\">Anmeldethread<\/a> im Forum. Fragen zum Projekt k\u00f6nnt ihr in Zukunft ebenfalls im Forum im entsprechenden <a href=\"https:\/\/forum.fanfiktion.de\/t\/54259\/1\">Organisationsthread<\/a> stellen. Vielen Dank! \ud83d\ude42<\/p>\n<hr \/>\n<p>Wir freuen uns sehr dar\u00fcber, wie viele positive R\u00fcckmeldungen wir auf Helges <a href=\"https:\/\/blog.fanfiktion.de\/blog\/4547\/wer-waere-bereit-tutorien-fuer-die-community-zu-erstellen\/#comment-31190\">Blogeintrag<\/a> erhalten haben \ud83d\ude42 Da wir das Ganze m\u00f6glichst schnell ins Rollen bringen wollen, m\u00f6chten wir hier ein paar organisatorische Dinge kl\u00e4ren. Im Anschluss wird es eine Liste der Themen geben, die ihr in den Kommentaren zum Blogeintrag vorgeschlagen habt.<\/p>\n<p><strong>Ich m\u00f6chte ein Tutorium zu einem Thema erstellen. Was muss ich tun?<br \/>\n<\/strong><br \/>\nMelde dich einfach unter diesem Blogeintrag. Gib bitte deinen Fanfiktion.de-Nutzernamen und das Thema an, zu dem du ein Tutorium erstellen m\u00f6chtest. Melde dich aber bitte nur dann, wenn du dir sicher bist, dass du etwas schreiben willst und kannst. Von &#8222;Vielleicht&#8220;-Anmeldungen bitten wir abzusehen. Nat\u00fcrlich kannst du dich auch f\u00fcr mehre Themen anmelden. Auch ist es kein Problem, wenn sich schon ein anderer Nutzer f\u00fcr das Thema angemeldet hat, zu dem du gerne ein Tutorium schreiben m\u00f6chtest.<\/p>\n<p><strong>Und dann?<\/strong><\/p>\n<p>Du kannst dann gern sofort loslegen. Schicke dein fertiges Tutorium bitte als Textdatei per Mail an folgende eMailadresse: <strong>gwenny@op.fanfiktion.de<\/strong><\/p>\n<p>Ich w\u00fcrde gern ein Tutorium zu einem Thema erstellen, das nicht in der Liste steht. Was muss ich tun?<\/p>\n<p>Das ist absolut kein Problem. Gib das Thema einfach in deinem Anmeldungskommentar an. Es wird dann in die Liste aufgenommen.<\/p>\n<p><strong>Wie sollte das Tutorium aussehen?<\/strong><\/p>\n<p>Da lassen wir euch freie Hand. Ihr solltet allerdings immer im Hinterkopf behalten, dass ein Tutorium eine Hilfe zu bestimmten Themen darstellt. Entsprechend sollten eure Texte auch leicht verst\u00e4ndlich und (besonders bei langen Texten) angenehm zu lesen sein. Zwar schauen wir vor dem Einbau eines Textes selbst noch einmal \u00fcber den Text, es w\u00e4re f\u00fcr uns aber eine gro\u00dfe Hilfe, wenn ihr ihn im Vornherein schon einmal von jemanden betalesen lassen w\u00fcrdet.<\/p>\n<p><strong>Die Themen<\/strong><\/p>\n<p><em>Planung:<\/em><\/p>\n<ul>\n<li>Wie organisiere ich meine Ideen?<\/li>\n<li>Von der Idee zur fertigen Geschichte.<\/li>\n<li>Wie recherchiere ich richtig?<\/li>\n<li>Wie plane ich ein Kapitel?<\/li>\n<li>Wie organisiere ich einen Text?<\/li>\n<li>Sollte eine Geschichte vor der Ver\u00f6ffentlichung beendet werden?<\/li>\n<li>In welchen Abst\u00e4nden sollte ein neues Kapitel ver\u00f6ffentlicht werden?<\/li>\n<li>Wo finde ich Ideen\/ Inspirationen f\u00fcr meine Geschichte?<\/li>\n<\/ul>\n<p><em>Charaktere:<\/em><\/p>\n<ul>\n<li>Wie vermeide ich Mary Sues \/ Gary Stues? <cite class=\"fn\">&#8211; <strong><em>Patchka<\/em><\/strong><\/cite><\/li>\n<li>Wie stelle ich glaubw\u00fcrdig Kinder unterschiedlichen Alters dar? &#8211; <em><strong>LetMeTellLies<\/strong><\/em><\/li>\n<li>Wie entwickle ich einen Hauptcharakter? &#8211; <strong><em>Autorin Ravenclaw<\/em><\/strong><\/li>\n<li>Nebencharaktere: Welche Typen d\u00fcrfen nicht fehlen und was macht sie so besonders?<\/li>\n<li>Wie erschaffe ich einen Charakter, den alle hassen? &#8211; <em><strong>Undertaker Phantom, Symphoniesoldat<\/strong><\/em><\/li>\n<li>Wie erschaffe ich einen Charakter, mit dem jeder mitf\u00fchlt? &#8211; <em><strong>Undertaker Phantom<\/strong><\/em><\/li>\n<li>Wie schaffe ich es, dass mein Hauptcharakter nicht zu perfekt wird?<\/li>\n<li>Welche Charaktertypen sind f\u00fcr gewisse Genres hilfreich? Welche eher l\u00e4stig?<\/li>\n<li>Wege aus der Stereotypenfalle. &#8211; <strong><em>Robidu<\/em><\/strong><\/li>\n<\/ul>\n<p><em>Form\/Stil:<\/em><\/p>\n<ul>\n<li>Wie formatiere ich passend? &#8211; <strong><em>Serena Hell<\/em><\/strong><\/li>\n<li>Wie vermeide ich Formatierungsfehler?<\/li>\n<li>Wie verhindere ich Ungereimtheiten bei l\u00e4ngeren Werken?<\/li>\n<li>Ab wann ist ein Betaleser notwendig\/hilfreich?<\/li>\n<li>Autorenkommentare\/Fragen unter\/\u00fcber dem Kapitel sinnvoll\/notwendig?<\/li>\n<\/ul>\n<p><em>Inhaltliches\/Handwerkliches:<\/em><\/p>\n<ul>\n<li>Wie erstellt man ein alternatives Universum (AU), das in sich schl\u00fcssig ist?<\/li>\n<li>Hilfe, ich bin beim Schreiben vom geplanten Plot abgekommen, was nun? &#8211; <em><strong>Crowley<\/strong><\/em><\/li>\n<li>Sachen, die man beim Weltenbau gerne vergisst. &#8211; <em><strong>Abidos, hotepneith<\/strong><\/em><\/li>\n<li>Wie finde ich den roten Faden in meiner Geschichte und wie kann ich verhindern, dass ich ihn wieder verliere? &#8211; <em><strong>OnePieceFreak<\/strong><\/em><\/li>\n<li>Wie vermeide ich, dass meine Kapitel zusammenhanglos wirken? &#8211; <strong><em>Ronja-Lii<\/em><\/strong><\/li>\n<li>Wie verleihe ich meiner Geschichte das richtige Tempo?<\/li>\n<li>Die Balance zwischen Dialog und Erz\u00e4hlung.<\/li>\n<li>Wie verhindere ich Ungereimtheiten bei l\u00e4ngeren Werken?<\/li>\n<li>Die richtige Erz\u00e4hlperspektive finden. &#8211; <em><strong>Thoronris<\/strong><\/em><\/li>\n<li>Welches Genre ist f\u00fcr welchen Schreibtyp am besten geeignet?<\/li>\n<li>Versteckte Hinweise am Anfang. Wie fallen sie nicht so auf? &#8211; <strong><cite class=\"fn\">Smaraya<\/cite><\/strong><\/li>\n<li>Wie schaffe ich es, dass meine Geschichte keine 0815-Geschichte wird?<\/li>\n<li>Andere B\u00fccher in meiner Geschichte erw\u00e4hnen. Gute Idee oder nicht?<\/li>\n<li>Wie gestalte ich einen Prolog interessant? &#8211; <em><strong>Crowley, Tears-of-Blood<\/strong><\/em><\/li>\n<li>Welche Prologtypen gibt es? &#8211; <em><strong>Crowley<\/strong><\/em><\/li>\n<li>Wie erzeuge ich einen Spannungsbogen?<\/li>\n<li>Wie vermeide ich Plotl\u00f6cher\/Logikfehler? &#8211; <strong><em>Tears-of-Blood<\/em><\/strong><\/li>\n<\/ul>\n<p><em>Fanfiction:<\/em><\/p>\n<ul>\n<li>Auf was muss ich achten, wenn ich Ideen von anderen Autoren \u00fcbernehme?<\/li>\n<li>Wie \u00fcbersetze ich Spielmechaniken glaubw\u00fcrdig in meine FF?<\/li>\n<li>Wie \u00fcbernehme ich glaubw\u00fcrdig Charaktere aus meiner Vorlage in meine FF? &#8211; <strong><cite class=\"fn\">Augurey, Patchka<\/cite><\/strong><\/li>\n<li>Wie \u00fcbernehme ich die Welt aus meiner Vorlage gut in meine FF? &#8211; <em><strong>Lukina<\/strong><\/em><\/li>\n<li>Wie schreibe ich eine Mitmach-Fanfiction (MMFF)? &#8211; <em><strong>Suki-chan\u00a0<\/strong><\/em><\/li>\n<li>Was kann ich tun, wenn sich der Charakter anders verhalten soll als in der Vorlage?<\/li>\n<li>Wie verkuppel ich gut Figuren, die sich in der Vorlage nicht m\u00f6gen?<\/li>\n<li>Wie \u00e4ndere ich in meiner Fanfiction Fakten der Vorlage ohne dass ein Bruch entsteht?<\/li>\n<li>Wie schreibe ich eine Reader-Fanfiction? &#8211; <em><strong>Patchka<\/strong><\/em><\/li>\n<li>Was kann ich tun, wenn sich der Charakter anders verhalten soll als in der Vorlage? &#8211; <em><strong>Augurey<\/strong><\/em><\/li>\n<li>Wie verkuppel ich Figuren, die sich in der Vorlage nicht m\u00f6gen? &#8211; <em><strong>Augurey<\/strong><\/em><\/li>\n<li>Wie \u00e4ndere ich in meiner Fanfiction Fakten der Vorlage ohne dass ein Bruch entsteht? &#8211; <em><strong>Augurey<br \/>\n<\/strong><\/em><\/li>\n<\/ul>\n<p><em>Reviews:<\/em><\/p>\n<ul>\n<li>Auf Reviews besser \u00f6ffentlich\/privat antworten?<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><em>Der Weg zum Verlag:<\/em><\/p>\n<ul>\n<li>Selbstverlag vs. herk\u00f6mmlicher Verlag. &#8211; <em><strong>Kakyuu, meteora99<\/strong><\/em><\/li>\n<li>Wie finde ich den richtigen Verlag f\u00fcr meine Nische (z.B. Homoerotik)? &#8211; <strong><em>Kakyuu<\/em><\/strong><\/li>\n<li>Wie ver\u00f6ffentliche ich im Selbstverlag? &#8211; <strong><em>Kakyuu<\/em><\/strong><\/li>\n<li>Wie gestaltet man ein Buch? &#8211; <em><strong>Kakyuu<\/strong><\/em><\/li>\n<li>Der Weg zum Verlag. &#8211; <em><strong>Kakyuu<\/strong><\/em><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p><strong>Nachtrag vom 08.03.2018 &#8211; 11:40 Uhr<\/strong><\/p>\n<p>Wie gew\u00fcnscht gibt es jetzt im Nachhilfe-Bereich unseres Forums Threads zum Projekt. F\u00fcr Organisatorisches, Fragen und Probleme nutzt bitte den <a href=\"https:\/\/forum.fanfiktion.de\/t\/54259\/1#jump5412658\">Organisationsthread<\/a>, f\u00fcr Anmeldungen oder Ideen zu weiteren Themen den <a href=\"https:\/\/forum.fanfiktion.de\/t\/54262\/1\">Anmeldethread<\/a> \ud83d\ude42<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nachtrag &#8211; 20.03.2018 Ich habe die Kommentarfunktion f\u00fcr diesen Beitrag geschlossen. Die Themenliste in diesem Beitrag wird NICHT MEHR aktualisiert. Die aktuelle Liste findet ihr im Anmeldethread im Forum. Fragen zum Projekt k\u00f6nnt ihr in Zukunft ebenfalls im Forum im entsprechenden Organisationsthread stellen. Vielen Dank! \ud83d\ude42 Wir freuen uns sehr dar\u00fcber, wie viele positive R\u00fcckmeldungen [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[81],"tags":[],"class_list":["post-5258","post","type-post","status-publish","format-standard","hentry","category-in-eigener-sache"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5GvD0-1mO","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/op.fanfiktion.de\/index.php\/wp-json\/wp\/v2\/posts\/5258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/op.fanfiktion.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/op.fanfiktion.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/op.fanfiktion.de\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/op.fanfiktion.de\/index.php\/wp-json\/wp\/v2\/comments?post=5258"}],"version-history":[{"count":8,"href":"https:\/\/op.fanfiktion.de\/index.php\/wp-json\/wp\/v2\/posts\/5258\/revisions"}],"predecessor-version":[{"id":5318,"href":"https:\/\/op.fanfiktion.de\/index.php\/wp-json\/wp\/v2\/posts\/5258\/revisions\/5318"}],"wp:attachment":[{"href":"https:\/\/op.fanfiktion.de\/index.php\/wp-json\/wp\/v2\/media?parent=5258"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/op.fanfiktion.de\/index.php\/wp-json\/wp\/v2\/categories?post=5258"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/op.fanfiktion.de\/index.php\/wp-json\/wp\/v2\/tags?post=5258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}